{"id":249,"date":"2024-07-09T14:40:40","date_gmt":"2024-07-09T14:40:40","guid":{"rendered":"https:\/\/renovamenergies.com\/politica-de-cookies\/"},"modified":"2025-09-13T03:45:53","modified_gmt":"2025-09-13T03:45:53","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"<section class=\"text_content_text_1_1 background-1-light\" data-block-id=\"6a978fdf44f026a978fdf44f03\">\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col\">\r\n                <div class=\"content-theme\">\r\n                                        <div class=\"texto color-1-headings-dark tamano7\">\r\n                        <h2 style='text-align: center'>POL\u00cdTICA DE COOKIES <br \/>\n        https:\/\/renovamenergies.com\/ca\/<\/h2>\n<p>        &nbsp;<\/p>\n<p>\n        El acceso a este Sitio Web puede implicar la utilizaci\u00f3n de cookies. Las cookies son peque\u00f1as cantidades de informaci\u00f3n que se almacenan en el navegador utilizado por cada Usuario \u2014en los distintos dispositivos que pueda utilizar para navegar\u2014 para que el servidor recuerde cierta informaci\u00f3n que posteriormente y \u00fanicamente el servidor que la implement\u00f3 leer\u00e1. Las cookies facilitan la navegaci\u00f3n, la hacen m\u00e1s amigable, y no da\u00f1an el dispositivo de navegaci\u00f3n.<\/p>\n<p>\n        Las cookies son procedimientos autom\u00e1ticos de recogida de informaci\u00f3n relativa a las preferencias determinadas por el Usuario durante su visita al Sitio Web con el fin de reconocerlo como Usuario, y personalizar su experiencia y el uso del Sitio Web, y pueden tambi\u00e9n, por ejemplo, ayudar a identificar y resolver errores.\n        <\/p>\n<p>\n        La informaci\u00f3n recabada a trav\u00e9s de las cookies puede incluir la fecha y hora de visitas al Sitio Web, las p\u00e1ginas visionadas, el tiempo que ha estado en el Sitio Web y los sitios visitados justo antes y despu\u00e9s del mismo. Sin embargo, ninguna cookie permite que esta misma pueda contactarse con el n\u00famero de tel\u00e9fono del Usuario o con cualquier otro medio de contacto personal. Ninguna cookie puede extraer informaci\u00f3n del disco duro del Usuario o robar informaci\u00f3n personal. La \u00fanica manera de que la informaci\u00f3n privada del Usuario forme parte del archivo Cookie es que el usuario d\u00e9 personalmente esa informaci\u00f3n al servidor.<\/p>\n<p>\n        Las cookies que permiten identificar a una persona se consideran datos personales. Por tanto, a las mismas les ser\u00e1 de aplicaci\u00f3n la Pol\u00edtica de Privacidad anteriormente descrita. En este sentido, para la utilizaci\u00f3n de las mismas ser\u00e1 necesario el consentimiento del Usuario. Este consentimiento ser\u00e1 comunicado, en base a una elecci\u00f3n aut\u00e9ntica, ofrecido mediante una decisi\u00f3n afirmativa y positiva, antes del tratamiento inicial, removible y documentado.<\/p>\n<p>        &nbsp;<\/p>\n<h4>Cookies propias<\/h4>\n<p>\n        Son aquellas cookies que son enviadas al ordenador o dispositivo del Usuario y gestionadas exclusivamente por Blog de MARC para el mejor funcionamiento del Sitio Web. La informaci\u00f3n que se recaba se emplea para mejorar la calidad del Sitio Web y su Contenido y su experiencia como Usuario. Estas cookies permiten reconocer al Usuario como visitante recurrente del Sitio Web y adaptar el contenido para ofrecerle contenidos que se ajusten a sus preferencias.<\/p>\n<p>        &nbsp;<\/p>\n<h4>Cookies de terceros<\/h4>\n<p>\n        Son cookies utilizadas y gestionadas por entidades externas que proporcionan a Blog de MARC servicios solicitados por este mismo para mejorar el Sitio Web y la experiencia del usuario al navegar en el Sitio Web. Los principales objetivos para los que se utilizan cookies de terceros son la obtenci\u00f3n de estad\u00edsticas de accesos y analizar la informaci\u00f3n de la navegaci\u00f3n, es decir, c\u00f3mo interact\u00faa el Usuario con el Sitio Web.<\/p>\n<p>\n        La informaci\u00f3n que se obtiene se refiere, por ejemplo, al n\u00famero de p\u00e1ginas visitadas, el idioma, el lugar a la que la direcci\u00f3n IP desde el que accede el Usuario, el n\u00famero de Usuarios que acceden, la frecuencia y reincidencia de las visitas, el tiempo de visita, el navegador que usan, el operador o tipo de dispositivo desde el que se realiza la visita. Esta informaci\u00f3n se utiliza para mejorar el Sitio Web, y detectar nuevas necesidades para ofrecer a los Usuarios un Contenido y\/o servicio de \u00f3ptima calidad. En todo caso, la informaci\u00f3n se recopila de forma an\u00f3nima y se elaboran informes de tendencias del Sitio Web sin identificar a usuarios individuales.<\/p>\n<p>\n        Puede obtener m\u00e1s informaci\u00f3n sobre las cookies, la informaci\u00f3n sobre la privacidad, o consultar la descripci\u00f3n del tipo de cookies que se utiliza, sus principales caracter\u00edsticas, periodo de expiraci\u00f3n, etc. en el siguiente(s) enlace(s):\n        <\/p>\n<p>\n        La(s) entidad(es) encargada(s) del suministro de cookies podr\u00e1(n) ceder esta informaci\u00f3n a terceros, siempre y cuando lo exija la ley o sea un tercero el que procese esta informaci\u00f3n para dichas entidades.\n        <\/p>\n<p>        &nbsp;<\/p>\n<h4>\n        Cookies de redes sociales<\/h4>\n<p>\n        Blog de MARC incorpora plugins de redes sociales, que permiten acceder a las mismas a partir del Sitio Web. Por esta raz\u00f3n, las cookies de redes sociales pueden almacenarse en el navegador del Usuario. Los titulares de dichas redes sociales disponen de sus propias pol\u00edticas de protecci\u00f3n de datos y de cookies, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad. El Usuario debe referirse a las mismas para informarse acerca de dichas cookies y, en su caso, del tratamiento de sus datos personales. \u00danicamente a t\u00edtulo informativo se indican a continuaci\u00f3n los enlaces en los que se pueden consultar dichas pol\u00edticas de privacidad y\/o de cookies:<\/p>\n<ul>\n<li>Facebook: <a href='https:\/\/www.facebook.com\/policies\/cookies\/'>https:\/\/www.facebook.com\/policies\/cookies\/<\/a><\/li>\n<li>Twitter: <a href='https:\/\/twitter.com\/es\/privacy'>https:\/\/twitter.com\/es\/privacy<\/a><\/li>\n<li>Instagram: <a href='https:\/\/help.instagram.com\/1896641480634370?ref=ig'>https:\/\/help.instagram.com\/1896641480634370?ref=ig<\/a><\/li>\n<li>YouTube: <a href='https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx'>https:\/\/policies.google.com\/privacy?hl=es-419&amp;gl=mx<\/a><\/li>\n<li>Pinterest: <a href='https:\/\/policy.pinterest.com\/es\/privacy-policy'>https:\/\/policy.pinterest.com\/es\/privacy-policy<\/a><\/li>\n<li>LinkedIn: <a href='https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies'>https:\/\/www.linkedin.com\/legal\/cookie-policy?trk=hp-cookies<\/a><\/li>\n<li>Deshabilitar, rechazar y eliminar cookies<\/li>\n<\/ul>\n<p>\n        El Usuario puede deshabilitar, rechazar y eliminar las cookies \u2014total o parcialmente\u2014 instaladas en su dispositivo mediante la configuraci\u00f3n de su navegador (entre los que se encuentran, por ejemplo, Chrome, Firefox, Safari, Explorer). En este sentido, los procedimientos para rechazar y eliminar las cookies pueden diferir de un navegador de Internet a otro. En consecuencia, el Usuario debe acudir a las instrucciones facilitadas por el propio navegador de Internet que est\u00e9 utilizando. En el supuesto de que rechace el uso de cookies \u2014total o parcialmente\u2014 podr\u00e1 seguir usando el Sitio Web, si bien podr\u00e1 tener limitada la utilizaci\u00f3n de algunas de las prestaciones del mismo.<\/p>\n<p>\n        Este documento de Pol\u00edtica de Cookies ha sido creado mediante el generador de plantilla de pol\u00edtica de cookies web gratis online el d\u00eda 18\/02\/2024.\n        <\/p>\n                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n<style>\r\n    .text_content_text_1_1 h1 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano1-font-size);\r\n        font-weight: var(--tamano1-font-weight);\r\n        line-height: var(--tamano1-line-height);\r\n        letter-spacing: var(--tamano1-letter-spacing);\r\n        font-family: var(--tamano1-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h2 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano2-font-size);\r\n        font-weight: var(--tamano2-font-weight);\r\n        line-height: var(--tamano2-line-height);\r\n        letter-spacing: var(--tamano2-letter-spacing);\r\n        font-family: var(--tamano2-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h3 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano3-font-size);\r\n        font-weight: var(--tamano3-font-weight);\r\n        line-height: var(--tamano3-line-height);\r\n        letter-spacing: var(--tamano3-letter-spacing);\r\n        font-family: var(--tamano3-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h4 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano4-font-size);\r\n        font-weight: var(--tamano4-font-weight);\r\n        line-height: var(--tamano4-line-height);\r\n        letter-spacing: var(--tamano4-letter-spacing);\r\n        font-family: var(--tamano4-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 ul,\r\n    .text_content_text_1_1 ol {\r\n        padding-left: 20px;\r\n    }\r\n\r\n    .text_content_text_1_1 .row .col {\r\n        padding-top: 75px;\r\n        width: 100%;\r\n    }\r\n\r\n\r\n    .text_content_text_1_1 .texto {\r\n        margin-bottom: 50px;\r\n    }\r\n\r\n    .text_content_text_1_1 .texto * {\r\n        padding-bottom: 20px;\r\n    }\r\n\r\n\r\n    .text_content_text_1_1 .row {\r\n        display: flex;\r\n        gap: 0px;\r\n    }\r\n\r\n    .text_content_text_1_1 {\r\n        position: relative;\r\n        background-position: center;\r\n        background-repeat: no-repeat;\r\n        background-size: cover;\r\n        padding: 81px 150px;\r\n        margin-top: -1px;\r\n    }\r\n\r\n    @media (max-width:1750px) {\r\n        .text_content_text_1_1 .row {\r\n            gap: 100px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1550px) {\r\n        .text_content_text_1_1 {\r\n            padding-left: 50px;\r\n            padding-right: 50px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1350px) {\r\n        .text_content_text_1_1 .row {\r\n            gap: 30px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1200px) {\r\n        .text_content_text_1_1 {\r\n            padding-left: 0;\r\n            padding-right: 0;\r\n        }\r\n    }\r\n\r\n    @media (max-width:992px) {\r\n        .text_content_text_1_1 .row .col-left {\r\n            padding-top: 0;\r\n            max-width: 100%;\r\n        }\r\n\r\n        .text_content_text_1_1 .texto {\r\n            margin-bottom: 35px;\r\n        }\r\n\r\n        .text_content_text_1_1 h2 {\r\n            padding-bottom: 40px;\r\n        }\r\n\r\n        .text_content_text_1_1 {\r\n            padding: 40px 0;\r\n        }\r\n\r\n        .text_content_text_1_1 h1 {\r\n            font-size: var(--tamano1-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h2 {\r\n            font-size: var(--tamano2-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h3 {\r\n            font-size: var(--tamano3-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h4 {\r\n            font-size: var(--tamano4-font-size-mobile);\r\n        }\r\n    }\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":1,"footnotes":""},"class_list":["post-249","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de Cookies - RENOVAM ENERGIES<\/title>\n<meta name=\"description\" content=\"Aprende c\u00f3mo utilizamos cookies para mejorar tu experiencia en RENOVAM ENERGIES. Descubre c\u00f3mo personalizamos contenido y garantizamos una navegaci\u00f3n segura.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Cookies - RENOVAM ENERGIES\" \/>\n<meta property=\"og:description\" content=\"Aprende c\u00f3mo utilizamos cookies para mejorar tu experiencia en RENOVAM ENERGIES. Descubre c\u00f3mo personalizamos contenido y garantizamos una navegaci\u00f3n segura.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"RENOVAM ENERGIES RENOVABLES\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-13T03:45:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Cookies - RENOVAM ENERGIES","description":"Aprende c\u00f3mo utilizamos cookies para mejorar tu experiencia en RENOVAM ENERGIES. Descubre c\u00f3mo personalizamos contenido y garantizamos una navegaci\u00f3n segura.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/","og_locale":"ca_ES","og_type":"article","og_title":"Pol\u00edtica de Cookies - RENOVAM ENERGIES","og_description":"Aprende c\u00f3mo utilizamos cookies para mejorar tu experiencia en RENOVAM ENERGIES. Descubre c\u00f3mo personalizamos contenido y garantizamos una navegaci\u00f3n segura.","og_url":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/","og_site_name":"RENOVAM ENERGIES RENOVABLES","article_modified_time":"2025-09-13T03:45:53+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/","url":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/","name":"Pol\u00edtica de Cookies - RENOVAM ENERGIES","isPartOf":{"@id":"https:\/\/renovamenergies.com\/ca\/#website"},"datePublished":"2024-07-09T14:40:40+00:00","dateModified":"2025-09-13T03:45:53+00:00","description":"Aprende c\u00f3mo utilizamos cookies para mejorar tu experiencia en RENOVAM ENERGIES. Descubre c\u00f3mo personalizamos contenido y garantizamos una navegaci\u00f3n segura.","breadcrumb":{"@id":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/renovamenergies.com\/ca\/politica-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/renovamenergies.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de cookies"}]},{"@type":"WebSite","@id":"https:\/\/renovamenergies.com\/ca\/#website","url":"https:\/\/renovamenergies.com\/ca\/","name":"RENOVAM ENERGIES RENOVABLES","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renovamenergies.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/pages\/249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/comments?post=249"}],"version-history":[{"count":3,"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/pages\/249\/revisions"}],"predecessor-version":[{"id":646,"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/pages\/249\/revisions\/646"}],"wp:attachment":[{"href":"https:\/\/renovamenergies.com\/ca\/wp-json\/wp\/v2\/media?parent=249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}